{"id":2164,"date":"2025-03-21T20:48:31","date_gmt":"2025-03-21T20:48:31","guid":{"rendered":"https:\/\/content.scienceofecd.com\/transcript\/?page_id=2164"},"modified":"2025-03-21T20:48:31","modified_gmt":"2025-03-21T20:48:31","slug":"transcript-clinton-bullying-fr","status":"publish","type":"page","link":"https:\/\/content.scienceofecd.com\/transcript\/transcript-clinton-bullying-fr\/","title":{"rendered":"Transcript Clinton \u2013 bullying &#8211; FR"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019un des signes qui nous permettent de constater que les choses ne vont pas aussi bien que nous le souhaitons pour nos enfants est le nombre de cas d\u2019intimidation que nous voyons dans la soci\u00e9t\u00e9. Et malheureusement, nous observons des cas d\u2019intimidation chez des enfants d\u2019\u00e0 peine quatre et cinq ans, des cas d\u2019insultes raciales, des cas d\u2019exclusion du jeu chez les jeunes enfants&nbsp;: nous ne voulons pas que tu joues avec nous, tu ne viens pas \u00e0 ma f\u00eate, donc des cas d\u2019agression relationnelle, et des cas d\u2019agression physique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais lorsque nous parlons d\u2019intimidation, nous parlons de la possibilit\u00e9 que les enfants de quatre, cinq ans et six ans utilisent un d\u00e9s\u00e9quilibre de pouvoir. Cela se produit tr\u00e8s t\u00f4t, les hi\u00e9rarchies dans le r\u00e9seau social commencent \u00e0 un tr\u00e8s jeune \u00e2ge. O\u00f9 voyons-nous l\u2019intimidation se produire le plus? Elle se produit en l\u2019absence d\u2019une culture adulte qui stipule que tout le monde a le droit de jouer. Elle se produit lorsque la culture adulte ne pr\u00f4ne pas comme valeur fondamentale que nous sommes une collectivit\u00e9 civique, peu importe si nous sommes un groupe de 5 ou de 55 personnes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donc, l\u2019intimidation dans le contexte de la garde d\u2019enfants est en grande partie, selon mon exp\u00e9rience, un reflet de ce que font les adultes. Quelles sont leurs pr\u00e9occupations premi\u00e8res? Si les \u00e9ducatrices s\u2019occupent de suivre les attentes du curriculum au lieu de s\u2019occuper du d\u00e9veloppement social et \u00e9motionnel des enfants, les r\u00e9sultats varieront. Si elles ne pr\u00eatent pas attention \u00e0 l\u2019intimidation, si elles croient qu\u2019il s\u2019agit uniquement d\u2019un rite de passage que les enfants lancent des insultes raciales ou excluent d\u2019autres enfants, si elles croient qu\u2019il s\u2019agit d\u2019un comportement normal chez les enfants, alors elles vont permettre ces comportements, et ceux-ci se multiplieront. Il faut donc vraiment s\u2019y attaquer en tant que groupe d\u2019adultes et avoir un dialogue \u00e0 ce sujet, en parler souvent avec les enfants. De plus, il existe de nombreux excellents livres pour mener des discussions avec les enfants au sujet de l\u2019intimidation et de ses r\u00e9percussions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019un des signes qui nous permettent de constater que les choses ne vont pas aussi bien que nous le souhaitons pour nos enfants est le nombre de cas d\u2019intimidation que nous voyons dans la soci\u00e9t\u00e9. Et malheureusement, nous observons des cas d\u2019intimidation chez des enfants d\u2019\u00e0 peine quatre et cinq ans, des cas d\u2019insultes raciales, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-text-only.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2164","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages\/2164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/comments?post=2164"}],"version-history":[{"count":1,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages\/2164\/revisions"}],"predecessor-version":[{"id":2165,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages\/2164\/revisions\/2165"}],"wp:attachment":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/media?parent=2164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}