{"id":1466,"date":"2025-03-05T22:24:41","date_gmt":"2025-03-05T22:24:41","guid":{"rendered":"https:\/\/content.scienceofecd.com\/transcript\/?page_id=1466"},"modified":"2025-03-21T15:43:52","modified_gmt":"2025-03-21T15:43:52","slug":"transcript-nelson-research-tools-2","status":"publish","type":"page","link":"https:\/\/content.scienceofecd.com\/transcript\/transcript-nelson-research-tools-2\/","title":{"rendered":"Transcript Nelson \u2013 research tools &#8211; FR"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans mon laboratoire, nous utilisons un certain nombre d\u2019outils pour \u00e9tudier le d\u00e9veloppement du cerveau chez les nourrissons et les enfants humains. Lorsque les enfants sont \u00e2g\u00e9s de moins de cinq ou six ans, nous nous concentrons principalement sur l\u2019enregistrement de l\u2019activit\u00e9 \u00e9lectrique du cerveau. Pour ce faire, nous pla\u00e7ons de petits dispositifs de d\u00e9tection sur la surface de la t\u00eate, soit avec un petit bonnet ou un filet. Et essentiellement, nous enregistrons l\u2019activit\u00e9 \u00e9lectrique qui se produit entre chaque neurone voisin ou cellule de cerveau voisine qui se d\u00e9place ensuite ou qui se propage \u00e0 la surface de la t\u00eate o\u00f9 nous avons plac\u00e9 les capteurs. Et cela nous r\u00e9v\u00e8le des informations sur les transactions qui se d\u00e9roulent \u00e0 chaque moment dans le cerveau d\u2019un b\u00e9b\u00e9 ou un jeune enfant alors qu\u2019il ou elle r\u00e9fl\u00e9chit. Maintenant, lorsque les enfants atteignent l\u2019\u00e2ge de cinq ou six ans, nous pouvons \u00e9galement commencer \u00e0 utiliser l\u2019imagerie par r\u00e9sonance magn\u00e9tique, en particulier l\u2019imagerie par r\u00e9sonance magn\u00e9tique fonctionnelle. Et la raison pour laquelle nous devons attendre \u00e0 cet \u00e2ge est que les enfants ont tendance \u00e0 beaucoup gigoter avant l\u2019\u00e2ge de cinq ou six ans. M\u00eame \u00e0 cinq ou six ans, c\u2019est parfois trop demander.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors ici, l\u2019enfant est allong\u00e9 dans un tunnel. Beaucoup de gens savent \u00e0 quoi ressemblent les appareils IRM. Et pendant qu\u2019ils sont dans ce tunnel, nous leur pr\u00e9sentons des images ou des sons et nous leur demandons de r\u00e9agir, par exemple, ils nous indiquent les images dont ils se souviennent en appuyant sur un bouton. La seule contrainte est que l\u2019enfant doit rester tr\u00e8s immobile. Nous ne pouvons pas tol\u00e9rer plus d\u2019un millim\u00e8tre de mouvement. Donc, pour un jeune enfant, m\u00eame s\u2019il croit qu\u2019il est rest\u00e9 immobile, en r\u00e9alit\u00e9, il a probablement fait quelques mouvements. Donc, selon notre exp\u00e9rience, une fois que les enfants arrivent \u00e0 l\u2019\u00e2ge d\u2019environ six ans, ils ont tendance \u00e0 \u00eatre capables de rester immobiles pendant dix ou quinze minutes \u00e0 la fois. En fait, nous trouvons qu\u2019il est beaucoup plus facile de tester les enfants dans ce domaine que de tester les adultes. En r\u00e8gle g\u00e9n\u00e9rale, les enfants ne sont jamais claustrophobes, ils aiment bien se trouver \u00e0 l\u2019int\u00e9rieur du tunnel. Si vous regardez les terrains de jeux de nos jours, vous remarquerez qu\u2019on y trouve beaucoup de petits tunnels \u00e9troits pour les enfants. Donc, ils sont un peu habitu\u00e9s \u00e0 cela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans mon laboratoire, nous utilisons un certain nombre d\u2019outils pour \u00e9tudier le d\u00e9veloppement du cerveau chez les nourrissons et les enfants humains. Lorsque les enfants sont \u00e2g\u00e9s de moins de cinq ou six ans, nous nous concentrons principalement sur l\u2019enregistrement de l\u2019activit\u00e9 \u00e9lectrique du cerveau. Pour ce faire, nous pla\u00e7ons de petits dispositifs de d\u00e9tection [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-text-only.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1466","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages\/1466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/comments?post=1466"}],"version-history":[{"count":3,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages\/1466\/revisions"}],"predecessor-version":[{"id":2055,"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/pages\/1466\/revisions\/2055"}],"wp:attachment":[{"href":"https:\/\/content.scienceofecd.com\/transcript\/wp-json\/wp\/v2\/media?parent=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}